{"id":4293,"date":"2018-06-06T17:50:03","date_gmt":"2018-06-06T22:50:03","guid":{"rendered":"http:\/\/posletrasufac.com\/?p=4293"},"modified":"2018-06-06T17:50:06","modified_gmt":"2018-06-06T22:50:06","slug":"uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli","status":"publish","type":"post","link":"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/","title":{"rendered":"Uso de aplicativo Whatsapp no ensino de L\u00edngua Inglesa \u00e9 tema de disserta\u00e7\u00e3o defendida no PPGLI"},"content":{"rendered":"<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"750\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/posletrasufac.com\\\/es\\\/2018\\\/06\\\/06\\\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\\\/&quot;,&quot;likes_blog_id&quot;:70821924}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 750px; height: 376px;\" data-original-width=\"750\" data-original-height=\"376\" > <div class=\"gallery-group images-1\" style=\"width: 500px; height: 376px;\" data-original-width=\"500\" data-original-height=\"376\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-04\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"496\"> <meta itemprop=\"height\" content=\"372\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4294\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-04.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.04\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-04.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-04.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-04.jpeg?w=496&#038;h=372&#038;ssl=1\" width=\"496\" height=\"372\" loading=\"lazy\" data-original-width=\"496\" data-original-height=\"372\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.04\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 496px; height: 372px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 250px; height: 376px;\" data-original-width=\"250\" data-original-height=\"376\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-06-1\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"246\"> <meta itemprop=\"height\" content=\"184\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4295\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06-1.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.06 (1)\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06-1.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06-1.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06-1.jpeg?w=246&#038;h=184&#038;ssl=1\" width=\"246\" height=\"184\" loading=\"lazy\" data-original-width=\"246\" data-original-height=\"184\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.06 (1)\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 246px; height: 184px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-06\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"246\"> <meta itemprop=\"height\" content=\"184\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4296\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.06\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-06.jpeg?w=246&#038;h=184&#038;ssl=1\" width=\"246\" height=\"184\" loading=\"lazy\" data-original-width=\"246\" data-original-height=\"184\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.06\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 246px; height: 184px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 750px; height: 142px;\" data-original-width=\"750\" data-original-height=\"142\" > <div class=\"gallery-group images-1\" style=\"width: 188px; height: 142px;\" data-original-width=\"188\" data-original-height=\"142\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-08-1\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"184\"> <meta itemprop=\"height\" content=\"138\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4297\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-08-1.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.08 (1)\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-08-1.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-08-1.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-08-1.jpeg?w=184&#038;h=138&#038;ssl=1\" width=\"184\" height=\"138\" loading=\"lazy\" data-original-width=\"184\" data-original-height=\"138\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.08 (1)\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 184px; height: 138px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 188px; height: 142px;\" data-original-width=\"188\" data-original-height=\"142\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-09-1\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"184\"> <meta itemprop=\"height\" content=\"138\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4298\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09-1.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.09 (1)\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09-1.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09-1.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09-1.jpeg?w=184&#038;h=138&#038;ssl=1\" width=\"184\" height=\"138\" loading=\"lazy\" data-original-width=\"184\" data-original-height=\"138\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.09 (1)\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 184px; height: 138px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 187px; height: 142px;\" data-original-width=\"187\" data-original-height=\"142\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-09\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"183\"> <meta itemprop=\"height\" content=\"138\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4299\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.09\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-09.jpeg?w=183&#038;h=138&#038;ssl=1\" width=\"183\" height=\"138\" loading=\"lazy\" data-original-width=\"183\" data-original-height=\"138\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.09\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 183px; height: 138px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 187px; height: 142px;\" data-original-width=\"187\" data-original-height=\"142\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/posletrasufac.com\/es\/2018\/06\/06\/uso-de-aplicativo-whatsapp-no-ensino-de-lingua-inglesa-e-tema-de-dissertacao-defendida-no-ppgli\/whatsapp-image-2018-06-04-at-13-22-10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"183\"> <meta itemprop=\"height\" content=\"138\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"4300\" data-orig-file=\"https:\/\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-10.jpeg\" data-orig-size=\"1280,960\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"WhatsApp Image 2018-06-04 at 13.22.10\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-10.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-10.jpeg?fit=750%2C563&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2018\/06\/whatsapp-image-2018-06-04-at-13-22-10.jpeg?w=183&#038;h=138&#038;ssl=1\" width=\"183\" height=\"138\" loading=\"lazy\" data-original-width=\"183\" data-original-height=\"138\" itemprop=\"http:\/\/schema.org\/image\" title=\"WhatsApp Image 2018-06-04 at 13.22.10\" alt=\"2018 - Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida\" style=\"width: 183px; height: 138px;\" \/> <\/a> <div class=\"tiled-gallery-caption\" itemprop=\"caption description\"> 2018 &#8211; Defesa de disserta\u00e7\u00e3o de Jo\u00e3o Itamar Melo de Almeida <\/div> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>Ocorreu na manh\u00e3 da \u00faltima segunda, 4, a defesa p\u00fablica de disserta\u00e7\u00e3o do aluno\u00a0Jo\u00e3o Itamar Melo de Almeida, cujo t\u00edtulo \u00e9<strong> &#8220;<\/strong><strong>As possibilidades pedag\u00f3gicas do aplicativo Whatsapp em um Curso de Letras Ingl\u00eas: sentidos constru\u00eddos durante uma experi\u00eancia de ensino da L\u00edngua Inglesa&#8221;<\/strong><\/p>\n<p>Participaram da Banca Examinadora a\u00a0Profa. Dra. Maristela Rosso Walker \u2013 Presidente\/Orientadora, a Profa. Dra. Valda In\u00eas Fontenele Pessoa \u00a0\u2013 Examinadora Interna (UFAC) e a Profa. Dra. Walkyria Alydia Grahl Passos Magno e Silva \u2013 Examinadora Externa (UFPA), via skype.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Ocorreu na manh\u00e3 da \u00faltima segunda, 4, a defesa p\u00fablica de disserta\u00e7\u00e3o do aluno\u00a0Jo\u00e3o Itamar Melo de Almeida, cujo t\u00edtulo \u00e9 &#8220;As possibilidades pedag\u00f3gicas do aplicativo Whatsapp em um Curso de Letras Ingl\u00eas: sentidos constru\u00eddos durante uma experi\u00eancia de ensino<\/p>","protected":false},"author":65883018,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[233475685],"tags":[],"class_list":["post-4293","post","type-post","status-publish","format-standard","hentry","category-ppgli"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4Na16-17f","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/posts\/4293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/users\/65883018"}],"replies":[{"embeddable":true,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/comments?post=4293"}],"version-history":[{"count":1,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/posts\/4293\/revisions"}],"predecessor-version":[{"id":4301,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/posts\/4293\/revisions\/4301"}],"wp:attachment":[{"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/media?parent=4293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/categories?post=4293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/posletrasufac.com\/es\/wp-json\/wp\/v2\/tags?post=4293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}