{"id":16636,"date":"2025-10-08T15:57:30","date_gmt":"2025-10-08T20:57:30","guid":{"rendered":"https:\/\/posletrasufac.com\/?p=16636"},"modified":"2025-10-08T18:09:18","modified_gmt":"2025-10-08T23:09:18","slug":"forum-de-editores-da-anpoll-se-reune-no-acre-e-lanca-carta-de-rio-branco","status":"publish","type":"post","link":"https:\/\/posletrasufac.com\/en\/2025\/10\/08\/forum-de-editores-da-anpoll-se-reune-no-acre-e-lanca-carta-de-rio-branco\/","title":{"rendered":"F\u00f3rum de Editores da Anpoll se re\u00fane no Acre e lan\u00e7a Carta de Rio Branco"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" data-attachment-id=\"16638\" data-permalink=\"https:\/\/posletrasufac.com\/en\/2025\/10\/08\/forum-de-editores-da-anpoll-se-reune-no-acre-e-lanca-carta-de-rio-branco\/dsc_3225\/\" data-orig-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?fit=4500%2C3000&amp;ssl=1\" data-orig-size=\"4500,3000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D7200&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1759234767&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DSC_3225\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?fit=750%2C500&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=750%2C500&#038;ssl=1\" alt=\"Grupo de pessoas posando para uma foto em um evento acad\u00eamico, com um banner ao fundo anunciando o V Encontro Nacional de Editores de Peri\u00f3dicos da \u00c1rea de Lingu\u00edstica e Literatura.\" class=\"wp-image-16638\" srcset=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3225.jpg?w=2250&amp;ssl=1 2250w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption class=\"wp-element-caption\"><strong>Bethania Mariani, Raquel Alves Ishii, Jos\u00e9 Magalh\u00e3es, Andr\u00e9 Rezende Benatti, Fernanda Correa Silveira Galli<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Editores e Editoras de peri\u00f3dicos cient\u00edficos da \u00c1rea de Lingu\u00edstica e Literatura de todo o pa\u00eds se reuniram na Universidade Federal do Acre (Ufac), no \u00faltimo dia 30 de setembro, por ocasi\u00e3o do V Encontro Nacional de Editores e da II Reuni\u00e3o do F\u00f3rum de Editores da ANPOLL (FEANPOLL).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Feanpoll \u00e9 atualmente coordenado pelas professoras Bethania Mariani (UFF), Raquel Alves Ishii (UFAC) e Fernanda Correa Silveira Galli (UFPE) e pelo professor Andr\u00e9 Rezende Benatti (UEMS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A programa\u00e7\u00e3o do evento contou com a participa\u00e7\u00e3o do Prof. Dr. Jos\u00e9 Magalh\u00e3es, Coordenador da \u00c1rea de Lingu\u00edstica e Literatura da CAPES que tratou do processo de avalia\u00e7\u00e3o de peri\u00f3dicos da \u00c1rea de Lingu\u00edstica e Literatura junto \u00e0 CAPES e seus novos crit\u00e9rios, e dos professores Frederico Augusto Garcia Fernandes (UEL) e S\u00f4nia Meneses (URCA) que debateram o tema \u201c\u00c9tica e integridade em publica\u00e7\u00f5es cient\u00edficas\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" data-attachment-id=\"16642\" data-permalink=\"https:\/\/posletrasufac.com\/en\/2025\/10\/08\/forum-de-editores-da-anpoll-se-reune-no-acre-e-lanca-carta-de-rio-branco\/dsc_3149\/\" data-orig-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?fit=4500%2C3000&amp;ssl=1\" data-orig-size=\"4500,3000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D7200&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1759226965&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;25&quot;,&quot;iso&quot;:&quot;640&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DSC_3149\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?fit=750%2C500&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=750%2C500&#038;ssl=1\" alt=\"Reuni\u00e3o de editores e editoras de peri\u00f3dicos cient\u00edficos em evento sobre Lingu\u00edstica e Literatura na Ufac, com mesa redonda e p\u00fablico atento.\" class=\"wp-image-16642\" srcset=\"https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=2048%2C1365&amp;ssl=1 2048w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=18%2C12&amp;ssl=1 18w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?resize=1200%2C800&amp;ssl=1 1200w, https:\/\/i0.wp.com\/posletrasufac.com\/wp-content\/uploads\/2025\/10\/DSC_3149.jpg?w=2250&amp;ssl=1 2250w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">O encontro marcou tamb\u00e9m a aprecia\u00e7\u00e3o e aprova\u00e7\u00e3o da Resolu\u00e7\u00e3o Feanpoll 01\/2025 que institui uma Pol\u00edtica de \u00c9tica e Integridade na pesquisa em peri\u00f3dicos da \u00c1rea de Lingu\u00edstica e Literatura, a partir das Diretrizes para a \u00c9tica na Pesquisa e a Integridade Cient\u00edfica do F\u00f3rum de Ci\u00eancias Humanas, Sociais, Sociais Aplicadas, Lingu\u00edstica, Letras e Artes (FCHSSALLA).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os participantes aprovaram ainda em plen\u00e1ria a \u201cCarta de Rio Branco\u201d, documento que ser\u00e1 encaminhado \u00e0s institui\u00e7\u00f5es brasileiras de ensino com recomenda\u00e7\u00f5es estruturantes para o reconhecimento e valoriza\u00e7\u00e3o do trabalho desenvolvido no \u00e2mbito da editora\u00e7\u00e3o cient\u00edfica \u2013 entre elas, a obrigatoriedade de incluir os peri\u00f3dicos no Plano de Desenvolvimento Institucional (PDI), a cria\u00e7\u00e3o de editais anuais de fomento e o reconhecimento da editora\u00e7\u00e3o cient\u00edfica na progress\u00e3o funcional docente, a cria\u00e7\u00e3o de campos de est\u00e1gio em editora\u00e7\u00e3o cient\u00edfica nos programas de p\u00f3s-gradua\u00e7\u00e3o e sugere que as universidades criem seus pr\u00f3prios \u201cF\u00f3runs de Peri\u00f3dicos\u201d vinculados \u00e0s Pr\u00f3-Reitorias de Pesquisa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Raquel Ishii, uma das coordenadoras do Feanpoll, j\u00e1 passa da hora de as universidades estabelecerem pol\u00edtica de editora\u00e7\u00e3o cient\u00edfica com fomento e reconhecimento formal dos profissionais que atuam na editora\u00e7\u00e3o: \u201cA maioria das institui\u00e7\u00f5es de ensino ignora o trabalho de editores e editoras, que segue volunt\u00e1rio e precarizado. Nas atuais condi\u00e7\u00f5es em que estamos, boa parte de nossos peri\u00f3dicos da \u00c1rea de Lingu\u00edstica e Literatura n\u00e3o consegue atender aos crit\u00e9rios estabelecidos por ag\u00eancias de fomento e avalia\u00e7\u00e3o, independente de serem crit\u00e9rios novos ou antigos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leia a \u00edntegra da carta de Rio Branco abaixo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CARTA DE RIO BRANCO AOS DIRIGENTES DAS IES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PELO ESTABELECIMENTO E CONSOLIDA\u00c7\u00c3O DE POL\u00cdTICAS EDITORIAIS DE PERI\u00d3DICOS CIENT\u00cdFICOS NO \u00c2MBITO DAS INSTITUI\u00c7\u00d5ES DE ENSINO SUPERIOR<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aos Senhores Reitores e Senhoras Reitoras das Institui\u00e7\u00f5es de Ensino Superior Brasileiras<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prezados Reitores e Reitoras,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O F\u00f3rum de Editores da Associa\u00e7\u00e3o Nacional de P\u00f3s-Gradua\u00e7\u00e3o e Pesquisa em Letras e Lingu\u00edstica \u2013 ANPOLL, reunindo editores de peri\u00f3dicos da \u00e1rea de Letras e Lingu\u00edstica, acompanhou e sistematizou os debates realizados em 2025 sobre pol\u00edticas editoriais e avalia\u00e7\u00e3o da produ\u00e7\u00e3o cient\u00edfica. A partir das discuss\u00f5es advindas dos encontros promovidos por este f\u00f3rum, a saber, \u201cM\u00e9tricas de avalia\u00e7\u00e3o de peri\u00f3dicos: impactos na avalia\u00e7\u00e3o da p\u00f3s-gradua\u00e7\u00e3o e os novos crit\u00e9rios da CAPES\u201d, com a Profa. Michely Jabala Mamede Vogel (UFF); \u201cEstrat\u00e9gias editoriais em Lingu\u00edstica e Literatura: pol\u00edticas de peri\u00f3dicos e exig\u00eancias de indexa\u00e7\u00e3o\u201d, com o Prof. Marcos Eduardo de Sousa (CEFET-MG\/UFOP); e \u201cObjetos editoriais e digitalidade: quest\u00f5es de fundo para a comunica\u00e7\u00e3o cient\u00edfica\u201d, com a Profa. Luciana Salazar Salgado (UFSCar), constru\u00edmos um conjunto de recomenda\u00e7\u00f5es estruturantes, as quais sugerimos que sejam acolhidas e implementadas pelas respectivas administra\u00e7\u00f5es superiores ou provid\u00eancias a serem tomadas no \u00e2mbito de cada institui\u00e7\u00e3o:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recomenda\u00e7\u00f5es gerais:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Inclus\u00e3o obrigat\u00f3ria dos peri\u00f3dicos cient\u00edficos no Plano de Desenvolvimento Institucional (PDI), com metas e indicadores claros de sustentabilidade, visibilidade e internacionaliza\u00e7\u00e3o.<\/li>\n\n\n\n<li>Institucionaliza\u00e7\u00e3o de pol\u00edticas editoriais estruturadas, que prevejam, no m\u00ednimo, um edital anual de fomento aos peri\u00f3dicos (via ag\u00eancias de fomento ou recursos or\u00e7ament\u00e1rios pr\u00f3prios), assegurando continuidade e previsibilidade.<\/li>\n\n\n\n<li>Valoriza\u00e7\u00e3o formal do trabalho editorial e da avalia\u00e7\u00e3o por pares, com previs\u00e3o de inser\u00e7\u00e3o no Plano\/Relat\u00f3rio de Atividades Docentes de modo a reconhecer horas dedicadas \u00e0 edi\u00e7\u00e3o, bem como a inclus\u00e3o dessas atividades nos crit\u00e9rios de progress\u00e3o funcional.<\/li>\n\n\n\n<li>Disponibiliza\u00e7\u00e3o, pelas pr\u00f3prias IES ou por meio de cons\u00f3rcios nacionais, de ferramentas e suporte t\u00e9cnico para coleta, an\u00e1lise e divulga\u00e7\u00e3o de m\u00e9tricas altim\u00e9tricas e de uso, fortalecendo a transpar\u00eancia e a governan\u00e7a dos peri\u00f3dicos.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Recomenda\u00e7\u00f5es espec\u00edficas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m das recomenda\u00e7\u00f5es gerais, propomos as seguintes a\u00e7\u00f5es estrat\u00e9gicas complementares, a serem adaptadas conforme a especificidade de cada universidade:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Instituir, apoiar e manter o F\u00f3rum de Peri\u00f3dicos como inst\u00e2ncia integrante da pol\u00edtica de Divulga\u00e7\u00e3o Cient\u00edfica e Populariza\u00e7\u00e3o da Ci\u00eancia da Universidade;<\/li>\n\n\n\n<li>Incentivar a participa\u00e7\u00e3o dos peri\u00f3dicos cient\u00edficos da IES no Portal de Peri\u00f3dicos da Universidade, a partir das pol\u00edticas propostas e aprovadas pelo F\u00f3rum de Peri\u00f3dicos, em conson\u00e2ncia com as demais inst\u00e2ncias da institui\u00e7\u00e3o;<\/li>\n\n\n\n<li>Formalizar e manter uma pol\u00edtica de pagamento de DOIs (Identificador de Objeto Digital) dos peri\u00f3dicos dos Programas de P\u00f3s-Gradua\u00e7\u00e3o disponibilizados no Portal de Peri\u00f3dicos.<\/li>\n\n\n\n<li>Garantir suporte t\u00e9cnico institucional para os peri\u00f3dicos, seja via N\u00facleo de Editora\u00e7\u00e3o, Biblioteca Universit\u00e1ria ou outra unidade competente;<\/li>\n\n\n\n<li>Apoiar os peri\u00f3dicos dos PPGs e demais revistas vinculadas a grupos de pesquisa e\/ou institutos, visando qualifica\u00e7\u00e3o e indexa\u00e7\u00e3o nas principais bases nacionais e internacionais (SciELO, Scopus, Web of Science, Latindex, etc.);<\/li>\n\n\n\n<li>Criar campos de est\u00e1gio curricular para demandas espec\u00edficas de editora\u00e7\u00e3o cient\u00edfica, contribuindo para a forma\u00e7\u00e3o de recursos humanos especializados e para a qualifica\u00e7\u00e3o das atividades do F\u00f3rum de Peri\u00f3dicos;<\/li>\n\n\n\n<li>Publicar editais internos espec\u00edficos voltados \u00e0 qualifica\u00e7\u00e3o dos peri\u00f3dicos cient\u00edficos, conforme disponibilidade de recursos e com apoio da coordena\u00e7\u00e3o do F\u00f3rum de Peri\u00f3dicos;<\/li>\n\n\n\n<li>Reconhecer e valorizar as contribui\u00e7\u00f5es dos editores de peri\u00f3dicos cient\u00edficos da universidade, criando indicadores objetivos que possam impactar positivamente a avalia\u00e7\u00e3o dessa atividade em editais internos e\/ou processos de progress\u00e3o funcional.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Contamos com o apoio de Vossas Senhorias para implementar as medidas propostas, fortalecendo a ci\u00eancia aberta, a qualidade editorial e o impacto social da pesquisa produzida em nossas institui\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rio Branco &#8211; Acre, 30 de setembro de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira aqui as fotos do Encontro do Feanpoll: <a href=\"https:\/\/drive.google.com\/drive\/folders\/1R5OxgYK3UDHBX9SsV546PRHLxDhtxlC2?usp=drive_link\">https:\/\/drive.google.com\/drive\/folders\/1R5OxgYK3UDHBX9SsV546PRHLxDhtxlC2?usp=drive_link<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Editores e Editoras de peri\u00f3dicos cient\u00edficos da \u00c1rea de Lingu\u00edstica e Literatura de todo o pa\u00eds se reuniram na Universidade Federal do Acre (Ufac), no \u00faltimo dia 30 de setembro, por ocasi\u00e3o do V Encontro Nacional de Editores e da<\/p>","protected":false},"author":65883018,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"Saiba como editores de peri\u00f3dicos em Lingu\u00edstica e Literatura se reuniram na Ufac para discutir pol\u00edticas e novas diretrizes editoriais.","jetpack_seo_html_title":"V Encontro Nacional de Editores em Lingu\u00edstica e Literatura","jetpack_seo_noindex":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[233475685],"tags":[],"class_list":["post-16636","post","type-post","status-publish","format-standard","hentry","category-ppgli"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_likes_enabled":false,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4Na16-4kk","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/posts\/16636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/users\/65883018"}],"replies":[{"embeddable":true,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/comments?post=16636"}],"version-history":[{"count":7,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/posts\/16636\/revisions"}],"predecessor-version":[{"id":16646,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/posts\/16636\/revisions\/16646"}],"wp:attachment":[{"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/media?parent=16636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/categories?post=16636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/posletrasufac.com\/en\/wp-json\/wp\/v2\/tags?post=16636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}